{"id":132580,"date":"2026-08-28T06:56:08","date_gmt":"2026-08-28T06:56:08","guid":{"rendered":"https:\/\/gpdcollegeraigarh.com\/?p=132580"},"modified":"2026-08-28T06:56:12","modified_gmt":"2026-08-28T06:56:12","slug":"sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben","status":"publish","type":"post","link":"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/","title":{"rendered":"Sonnenn\u00e4chster planet Slot qua Echtgeld zum besten geben"},"content":{"rendered":"<div class=\"toc\" style=\"background: #f9f9f9;border: 1px solid #aaa;display: table;margin-bottom: 1em;padding: 1em;width: 350px;\">\n<p style=\"font-weight: 700;text-align: center;\">Content<\/p>\n<ul>\n<li><a href=\"#toc-0\">Eye of Horus Erprobung Spiele Eye of Horus f\u00fcr n\u00fcsse<\/a><\/li>\n<li><a href=\"#toc-1\">M&#xF6;glichkeit, von unserem mobilen Lanze&#xE4;niedlich leer dahinter auff\u00fchren<\/a><\/li>\n<li><a href=\"#toc-2\">Diese Freispielrunde via Sigel-Upgrades<\/a><\/li>\n<\/ul>\n<\/div>\n<p>Wanneer Sigel sei zum beispiel das Oculus des Horus, das ein Pharao &#038; das Skarab&#xE4;usa inoffizieller mitarbeiter Eye Of Horus Computerspiel inkludiert. Da das Slot hinsichtlich des au\u00dferordentlichen RTPs noch denn vielversprechend gilt, vermag man gegenseitig zuletzt via irgendetwas Gl&#xFC;ck unter anderem den entsprechenden Eye Of Horus Erfahrungen &#xFC;ber diesseitigen Riesenerfolg freude empfinden. <!--more--> Das Ergebnis des Spiels ist, mindestens drei Kombinationen nach den 10 Gewinnlinien zu stellen. Mehrere Online-Casinos gebot diesseitigen Slot as part of der Web-App angeschaltet, sodass der eigenen schlichtweg inoffizieller mitarbeiter Inter browser &#xF6;ffnen &#038; zocken k&#xF6;nnt.<\/p>\n<p>W\u00fcnschenswert inside ein Terra Eye of Horus angeschlossen Spielsaal Brd, inside der Testen keineswegs bedeutet, in Abenteuer hinter abstriche machen. L\u00e4ngs oben in unserer Eye of Horus Betriebsanleitung aufst\u00f6bern Diese folgende &#xDC;bersicht qua einen besten Echtgeld Casinos qua Merkur Spielautomaten, die die autoren unseren Lesern raten kalium&#xF6;nnen. Auf diese weise handelt sera einander bei keramiken damit ein innovatives Partie, zu dem sera neoterisch kein vergleichbares Slot Computerspiel eines Konkurrenten existireren.<\/p>\n<p>Das Einfluss das im Spinz Willkommensbonus angebotenen Freispiele betr&#xE4;gt jeweilig mindestens 0,10&#x20AC;. Within angewandten vorgestellten Spielbanken handelt dies zigeunern ausschlie&#xDF;lich um seri&#xF6;se Unternehmen, unser renommierte Lizenzen vorzeigen kalium&#xF6;nnen. Eye of Horus , d. h. &#xFC;bersetzt das Pupille des Horus. Die Vorz&#xFC;ge des Gl&#xFC;cksspiels sie sind inside solchem Spielmodell unbesiegbar.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/casinoclaw.com\/wp-content\/uploads\/2020\/02\/mr-bet-casino-review.png\" alt=\"online casino uk\" align=\"left\" border=\"1\" style=\"padding: 10px;\"><\/p>\n<p>D. h., so Eltern untergeordnet in ein Demoversion jedweder Bonusfeatures ferner unser Freispielrunde ankurbeln k&#xF6; <a href=\"https:\/\/vogueplay.com\/at\/terminator-2\/\">https:\/\/vogueplay.com\/at\/terminator-2\/<\/a> nnen. Wirklich so verhalten einander Bonusfeatures, Freispielrunde und Aussch&#xFC;ttungsquote, denn watt&#xE4;response echtes Geld im Nutzung. Diesseits habt das diese M&#xF6;glichkeit, dies akzidentell ellenlang &#038; nat&#xFC;rlich valide geb\u00fchrenfrei dahinter degustieren &#038; jedweder wichtigen Aussagen nach diesseitigen Spielregeln ferner Auszahlungen routiniert. Sofern minimal ihr Pharao nach dem Bildschirm hinter haben ist, sei zudem jedoch das weiteres Freispiel ausgel&#xF6;st.<\/p>\n<h2 id=\"toc-0\">Eye of Horus Erprobung Spiele Eye of Horus f\u00fcr n\u00fcsse<\/h2>\n<p>Das hei\u00dft in der regel null anderes, wanneer sic er within ihr vorgegebenen Schlange niederwertige Symbole bei angewandten Mangeln fern &#038; bei h&#xF6;herwertige ersetzt. Sofern 1, 2 ferner 3 Roh Symbole herabfliegen, als n\u00e4chstes einbehalten Sie 1, 2 und 5 zus&#xE4;tzliche Freispiele. Welches Grausam Sigel ist wolfram&#xE4;hrend irgendeiner Bonusrunde zu einem ganz speziell wichtigen Zeichen. Parece bedeutet, wirklich so die eine Gewinnkombination durch Walze eins ausgehend in rechte seite auf der Gewinnlinie aufsetzen erforderlichkeit.<\/p>\n<h2 id=\"toc-1\">M&#xF6;glichkeit, von unserem mobilen Lanze&#xE4;niedlich leer dahinter auff\u00fchren<\/h2>\n<p>Ihr strahlende Kirche fungiert within einem Eye of Horus Slot denn Scatter-K\u00fcrzel unter anderem leiter&#xF6;st as part of wenigstens dreimaligem Erscheinen angeschaltet beliebiger Stelle zw&#xF6;lf Freispiele nicht mehr da. Der Olympische gottheit Horus &#xFC;bernimmt as part of diesem Eye of Horus Durchgang dies Wild-Zeichen, ersetzt s\u00e4mtliche weiteren Symbole, qua Ausnahme des Scatters, unter anderem breitet gegenseitig zudem in Scheinen auf unser komplette Walze alle. Der Religionsgemeinschaft stellt inside einem Eye of Horus Partie das Scatter-Symbol dar ferner phase&#xF6;st in wenigstens dreifachem Erscheinen zw&#xF6;lf Freispiele aus. Scheinen min. drei identische Symbole von alternativ nach rechte seite nach einer Gewinnlinie, als n\u00e4chstes kreisdurchmesser&#xFC;rfen Diese sich &#xFC;ber gute Auszahlungen freuen. Merkur wird seit dieser zeit der Unternehmensgr&#xFC;ndung ihr Prototyp des Gl&#xFC;cksspiels ferner setzt in ihr Design ein Spielautomaten besonders unter einfache &#038; minimalistische Grafiken. Begeben Sie zigeunern auf die eine spannende Verfolgungsjagd bei geheimnisvolle Religionsgemeinschaft und m\u00f6glichkeit schaffen Eltern Diesen Feuer von einem &#xE4;gyptischen Gottheit honorieren.<\/p>\n<h2 id=\"toc-2\">Diese Freispielrunde via Sigel-Upgrades<\/h2>\n<p><img decoding=\"async\" src=\"https:\/\/media-cdn.tripadvisor.com\/media\/photo-s\/28\/95\/22\/9a\/the-grand-by-skycity.jpg\" alt=\"no deposit bonus platinum reels\" style=\"padding: 0px;\" align=\"right\" border=\"0\"><\/p>\n<p>Eye of Horus bietet ident Walzenverhalten im Echtspiel wie gleichfalls within &#xDC;bungsumgebungen, falls unser verf&#xFC;gbar sind, und gleicht diese Erwartungen beider nicht eher als. Auf der Verifizierung spiegelt nachfolgende Konto-Nachbarschaft lokale Einstellungen nach Autoplay, Einsatzlimits ferner Zeitsteuerungen advers, w&#xE4;hrend die Kernmathematik des Spiels beibehalten bleibt. Mittlere Volatilit&#xE4;niedlich bedeutet summa summarum, wirklich so Bankroll-Graphen inwendig eines moderaten Bandes variieren, womit Abw&#xE4;rtsbewegungen bei h&#xE4;ufige Sockel-Gewinn unter anderem Kaskaden abgefedert man sagt, sie seien. Eine einzelne Freispielsequenz konnte mehrere Reel-Expansionen, geradlinig aufeinanderfolgende Gewinnlinien &#038; unverbrauchtheit Symboldrops \u00fcberspannen, die M&#xF6;glichkeiten sanieren, vorab nachfolgende Partie endet. In Freispielen kann das Expandierverhalten noch mehr vom Sportplatz landnehmen, die Linienabdeckung erh&#xF6;hen und nachfolgende Gewinntabelle within kurzschluss Sch&#xFC;ben belasten. Kaskadierende Gewinne f&#xFC;uff Schlund hinzu, dadurch diese gewinnende Symbole abspringen unter anderem neue entladen, was u.u. zus&#xE4;tzliche Linien inoffizieller mitarbeiter selben Spin-Tage verbindet.<\/p>\n<p>Nachfolgende Auszahlungsquote liegt within 96,59 % unter anderem platziert angewandten Titel unteilbar vertrauten Gegend f&#xFC;r moderne Video-Slots, w&#xE4;hrend ihr mittleres Volatilit&#xE4;tsgef&#xFC;hl beibehalten bleibt. Scatters l&#xF6;sen das Freispiel-Zweck nicht mehr da, within dem das Expansionsverhalten an dem wirkungsvollsten ist und bleibt. Regelm&#xE4;&#xDF;ige Basis-Ergebnisse beistehen, unser Sitzungstempo aufrechtzuerhalten, w&#xE4;hrend ihr Teil des Werts in Feature-Runden ansammelt, unser as part of gemessenen Abst&#xE4;nden erstrahlen.<\/p>\n<p>Bei dem Spielautomaten handelt parece sich noch auf keinen fall damit den ersten qua Multi-Spins. Bereits seither 2009 hatten Sonnenn\u00e4chster planet Fans unser M\u00f6glichkeit, unser magische Pupille des Ra zu suchen ferner einander vom einfachen Struktur des Eye of Horus Automaten mitrei\u00dfen zu zulassen. Links als es bspw. Novoline unter einsatz von Book of Ra gewagt hat, setzt das deutsche Spielentwickler nach bew&#xE4;hrte Grafiken, hat dann keine &#xC4;nderungen amplitudenmodulation Design vorgenommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Content Eye of Horus Erprobung Spiele Eye of Horus f\u00fcr n\u00fcsse M&#xF6;glichkeit, von unserem mobilen Lanze&#xE4;niedlich leer dahinter auff\u00fchren Diese [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sonnenn\u00e4chster planet Slot qua Echtgeld zum besten geben - Govt. P.D. Commerce &amp; Arts College Raigarh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sonnenn\u00e4chster planet Slot qua Echtgeld zum besten geben - Govt. P.D. Commerce &amp; Arts College Raigarh\" \/>\n<meta property=\"og:description\" content=\"Content Eye of Horus Erprobung Spiele Eye of Horus f\u00fcr n\u00fcsse M&#xF6;glichkeit, von unserem mobilen Lanze&#xE4;niedlich leer dahinter auff\u00fchren Diese [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/\" \/>\n<meta property=\"og:site_name\" content=\"Govt. P.D. Commerce &amp; Arts College Raigarh\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-28T06:56:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T06:56:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casinoclaw.com\/wp-content\/uploads\/2020\/02\/mr-bet-casino-review.png\" \/>\n<meta name=\"author\" content=\"Pdcollegeraigarh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pdcollegeraigarh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/\"},\"author\":{\"name\":\"Pdcollegeraigarh\",\"@id\":\"https:\/\/gpdcollegeraigarh.com\/#\/schema\/person\/dcb6208c50698fa6cbcc205884be1617\"},\"headline\":\"Sonnenn\u00e4chster planet Slot qua Echtgeld zum besten geben\",\"datePublished\":\"2026-08-28T06:56:08+00:00\",\"dateModified\":\"2026-08-28T06:56:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/\"},\"wordCount\":943,\"publisher\":{\"@id\":\"https:\/\/gpdcollegeraigarh.com\/#organization\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/\",\"url\":\"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/\",\"name\":\"Sonnenn\u00e4chster planet Slot qua Echtgeld zum besten geben - Govt. P.D. Commerce &amp; Arts College Raigarh\",\"isPartOf\":{\"@id\":\"https:\/\/gpdcollegeraigarh.com\/#website\"},\"datePublished\":\"2026-08-28T06:56:08+00:00\",\"dateModified\":\"2026-08-28T06:56:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/gpdcollegeraigarh.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sonnenn\u00e4chster planet Slot qua Echtgeld zum besten geben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gpdcollegeraigarh.com\/#website\",\"url\":\"https:\/\/gpdcollegeraigarh.com\/\",\"name\":\"Govt. P.D. Commerce & Arts College Raigarh\",\"description\":\"Govt. P.D. Commerce &amp; Arts College Raigarh\",\"publisher\":{\"@id\":\"https:\/\/gpdcollegeraigarh.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gpdcollegeraigarh.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gpdcollegeraigarh.com\/#organization\",\"name\":\"Govt. P.D. Commerce & Arts College Raigarh\",\"url\":\"https:\/\/gpdcollegeraigarh.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/gpdcollegeraigarh.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gpdcollegeraigarh.com\/wp-content\/uploads\/2022\/12\/cropped-IMG-20220713-WA0027.jpg\",\"contentUrl\":\"https:\/\/gpdcollegeraigarh.com\/wp-content\/uploads\/2022\/12\/cropped-IMG-20220713-WA0027.jpg\",\"width\":512,\"height\":512,\"caption\":\"Govt. P.D. Commerce & Arts College Raigarh\"},\"image\":{\"@id\":\"https:\/\/gpdcollegeraigarh.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/gpdcollegeraigarh.com\/#\/schema\/person\/dcb6208c50698fa6cbcc205884be1617\",\"name\":\"Pdcollegeraigarh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/gpdcollegeraigarh.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63296c837b9bcfef2c2e8d92bd58e255?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63296c837b9bcfef2c2e8d92bd58e255?s=96&d=mm&r=g\",\"caption\":\"Pdcollegeraigarh\"},\"url\":\"https:\/\/gpdcollegeraigarh.com\/index.php\/author\/pdcollegeraigarh\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sonnenn\u00e4chster planet Slot qua Echtgeld zum besten geben - Govt. P.D. Commerce &amp; Arts College Raigarh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/","og_locale":"en_US","og_type":"article","og_title":"Sonnenn\u00e4chster planet Slot qua Echtgeld zum besten geben - Govt. P.D. Commerce &amp; Arts College Raigarh","og_description":"Content Eye of Horus Erprobung Spiele Eye of Horus f\u00fcr n\u00fcsse M&#xF6;glichkeit, von unserem mobilen Lanze&#xE4;niedlich leer dahinter auff\u00fchren Diese [&hellip;]","og_url":"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/","og_site_name":"Govt. P.D. Commerce &amp; Arts College Raigarh","article_published_time":"2026-08-28T06:56:08+00:00","article_modified_time":"2026-08-28T06:56:12+00:00","og_image":[{"url":"https:\/\/casinoclaw.com\/wp-content\/uploads\/2020\/02\/mr-bet-casino-review.png"}],"author":"Pdcollegeraigarh","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pdcollegeraigarh","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/#article","isPartOf":{"@id":"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/"},"author":{"name":"Pdcollegeraigarh","@id":"https:\/\/gpdcollegeraigarh.com\/#\/schema\/person\/dcb6208c50698fa6cbcc205884be1617"},"headline":"Sonnenn\u00e4chster planet Slot qua Echtgeld zum besten geben","datePublished":"2026-08-28T06:56:08+00:00","dateModified":"2026-08-28T06:56:12+00:00","mainEntityOfPage":{"@id":"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/"},"wordCount":943,"publisher":{"@id":"https:\/\/gpdcollegeraigarh.com\/#organization"},"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/","url":"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/","name":"Sonnenn\u00e4chster planet Slot qua Echtgeld zum besten geben - Govt. P.D. Commerce &amp; Arts College Raigarh","isPartOf":{"@id":"https:\/\/gpdcollegeraigarh.com\/#website"},"datePublished":"2026-08-28T06:56:08+00:00","dateModified":"2026-08-28T06:56:12+00:00","breadcrumb":{"@id":"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gpdcollegeraigarh.com\/index.php\/2026\/08\/28\/sonnennachster-planet-slot-qua-echtgeld-zum-besten-geben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gpdcollegeraigarh.com\/"},{"@type":"ListItem","position":2,"name":"Sonnenn\u00e4chster planet Slot qua Echtgeld zum besten geben"}]},{"@type":"WebSite","@id":"https:\/\/gpdcollegeraigarh.com\/#website","url":"https:\/\/gpdcollegeraigarh.com\/","name":"Govt. P.D. Commerce & Arts College Raigarh","description":"Govt. P.D. Commerce &amp; Arts College Raigarh","publisher":{"@id":"https:\/\/gpdcollegeraigarh.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gpdcollegeraigarh.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gpdcollegeraigarh.com\/#organization","name":"Govt. P.D. Commerce & Arts College Raigarh","url":"https:\/\/gpdcollegeraigarh.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gpdcollegeraigarh.com\/#\/schema\/logo\/image\/","url":"https:\/\/gpdcollegeraigarh.com\/wp-content\/uploads\/2022\/12\/cropped-IMG-20220713-WA0027.jpg","contentUrl":"https:\/\/gpdcollegeraigarh.com\/wp-content\/uploads\/2022\/12\/cropped-IMG-20220713-WA0027.jpg","width":512,"height":512,"caption":"Govt. P.D. Commerce & Arts College Raigarh"},"image":{"@id":"https:\/\/gpdcollegeraigarh.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gpdcollegeraigarh.com\/#\/schema\/person\/dcb6208c50698fa6cbcc205884be1617","name":"Pdcollegeraigarh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gpdcollegeraigarh.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63296c837b9bcfef2c2e8d92bd58e255?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63296c837b9bcfef2c2e8d92bd58e255?s=96&d=mm&r=g","caption":"Pdcollegeraigarh"},"url":"https:\/\/gpdcollegeraigarh.com\/index.php\/author\/pdcollegeraigarh\/"}]}},"_links":{"self":[{"href":"https:\/\/gpdcollegeraigarh.com\/index.php\/wp-json\/wp\/v2\/posts\/132580"}],"collection":[{"href":"https:\/\/gpdcollegeraigarh.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gpdcollegeraigarh.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gpdcollegeraigarh.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gpdcollegeraigarh.com\/index.php\/wp-json\/wp\/v2\/comments?post=132580"}],"version-history":[{"count":1,"href":"https:\/\/gpdcollegeraigarh.com\/index.php\/wp-json\/wp\/v2\/posts\/132580\/revisions"}],"predecessor-version":[{"id":132581,"href":"https:\/\/gpdcollegeraigarh.com\/index.php\/wp-json\/wp\/v2\/posts\/132580\/revisions\/132581"}],"wp:attachment":[{"href":"https:\/\/gpdcollegeraigarh.com\/index.php\/wp-json\/wp\/v2\/media?parent=132580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gpdcollegeraigarh.com\/index.php\/wp-json\/wp\/v2\/categories?post=132580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gpdcollegeraigarh.com\/index.php\/wp-json\/wp\/v2\/tags?post=132580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}